{"id":1337,"date":"2017-07-31T08:33:42","date_gmt":"2017-07-31T08:33:42","guid":{"rendered":"http:\/\/mecanicacuriel.com\/?p=1337"},"modified":"2018-10-31T17:06:27","modified_gmt":"2018-10-31T17:06:27","slug":"que-es-una-fabrica-de-mecanizados-en-barcelona","status":"publish","type":"post","link":"https:\/\/mecanicacuriel.com\/en\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/","title":{"rendered":"What is a machining factory in Barcelona?"},"content":{"rendered":"<p align=\"justify\">Bienvenidos un d\u00eda m\u00e1s al blog de Mec\u00e1nica Curiel, una <strong>machining factory<\/strong> situada en <strong>Barcelona<\/strong> desde el a\u00f1o 1972, los cuales ofrecen a sus clientes la fabricaci\u00f3n y la construcci\u00f3n de diferentes tipos de <strong>mechanized<\/strong> y de montajes de precisi\u00f3n. Pero todav\u00eda hay mucha gente en <strong>Barcelona<\/strong> que no conoce la gran importancia que tienen las <strong>machining factories<\/strong>, ya que no acaban de entender cu\u00e1l es la funci\u00f3n y el trabajo que realizan, por esta misma raz\u00f3n, en el nuevo art\u00edculo de hoy, os queremos hablar de cu\u00e1l es el trabajo que realizamos en nuestra <strong>machining factory<\/strong> in <strong>Barcelona<\/strong>, quienes somos unos referentes en este sector.<\/p>\n<p align=\"justify\">At our <strong>machining factory in Barcelona<\/strong>, nos encargamos de elaborar todo tipo de aparatos \u00fatiles f\u00edsicos de <strong>mechanized<\/strong> de precisi\u00f3n, de laboratorio, de mec\u00e1nicas para viscosimetr\u00eda y electromedicina, de peque\u00f1a maquinaria en general, de valvuler\u00eda especial, de utillajes y de prototipos. Esto, lo hacemos a partir de diferentes materiales muy resistentes, que variar\u00e1n seg\u00fan la demanda y las necesidades de cada uno de nuestros clientes de <strong>Barcelona<\/strong>, ya que en nuestra <strong>factory<\/strong> <strong>of machining<\/strong>, contamos con un gran servicio de asesoramiento t\u00e9cnico, con tal de que puedan obtener los mejores resultados. Algunos de los materiales m\u00e1s utilizados en nuestra <strong>machining factory in Barcelona<\/strong>, es el acero inoxidable, el bronce y el pl\u00e1stico t\u00e9cnico.<\/p>\n<p align=\"justify\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1338 alignleft\" src=\"http:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-1-1.jpg\" alt=\"\" width=\"477\" height=\"317\" srcset=\"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-1-1.jpg 960w, https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-1-1-300x199.jpg 300w, https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-1-1-768x510.jpg 768w\" sizes=\"auto, (max-width: 477px) 100vw, 477px\" \/>Sin ninguna duda, la principal funci\u00f3n que hacemos en nuestra <strong>machining factory<\/strong> in <strong>Barcelona<\/strong>, es la confecci\u00f3n de aparatos <strong>mechanized<\/strong>, los cuales son muy diferentes entre ellos y por lo tanto se utilizan para una gran cantidad de sectores diferentes, los cuales son necesarios para toda la sociedad.<\/p>\n<p align=\"justify\">Pero, en nuestra fabrica de <strong>mechanized in Barcelona<\/strong>, no nos conformamos con hacer lo mismo que el resto, si no que vamos un paso m\u00e1s all\u00e1, ofreciendo un servicio de calidad de la mano de grandes profesionales y ofreciendo una calidad excelente, gracias a la utilizaci\u00f3n de grandes avances tecnol\u00f3gicos y estando siempre a la \u00faltima, de esta forma todos y cada uno de nuestros clientes podr\u00e1n estar satisfechos, y seguir\u00e1n confiando en nuestra fabrica de <strong>mechanized in Barcelona<\/strong>, para sus futuros proyectos.<\/p>\n<p align=\"justify\">De esta forma, es como hemos ido consiguiendo la gran lista de clientes satisfecho con la cual contamos ahora y que despu\u00e9s de cuarenta a\u00f1os, siguen confiando en todos nuestros trabajos, en nuestros profesionales t\u00e9cnicos, en nuestros consejos y en la filosof\u00eda tan firme que tenemos desde el principio, basada en tres pilares, la seriedad, el compromiso y la profesionalidad. As\u00ed que si quieres saber m\u00e1s sobre nuestra <strong>factory<\/strong> <strong>de mecanizados en Barcelona,<\/strong> o sobre los servicios que os podemos ofrecer, no os lo pens\u00e9is ni un segundo m\u00e1s y poneros en contacto con nosotros.<\/p>","protected":false},"excerpt":{"rendered":"<p>Welcome one more day to the blog of Mec\u00e1nica Curiel, a machining factory located in Barcelona since 1972, which offers its clients the manufacture and construction of different types of machining and precision assemblies. But there are still many people in Barcelona who do not know the great importance of machining factories,<\/p>\n<div class=\"h10\"><\/div>\n<p><a class=\"more-link1\" href=\"https:\/\/mecanicacuriel.com\/en\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/\">Read more<\/a><\/p>","protected":false},"author":4,"featured_media":1339,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,4,5,8,123,10,15,16],"tags":[20,21,23,24,28,122,29,121,30,31,32,33,34,39,40,41,42,43,44,49],"class_list":["post-1337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresa-de-mecanizados","category-empresa-mecanizados","category-empresa-mecanizados-barcelona","category-empresa-valvuleria-barcelona","category-fabrica-mecanizados-barcelona","category-mecanizados-cnc-barcelona","category-mecanizados-precision","category-mecanizados-precision-barcelona-2","tag-barcelona","tag-cnc","tag-empresa-de-mecanizados","tag-empresa-de-mecanizados-barcelona","tag-empresa-mecanizados-tarragona","tag-fabrica-mecanizados-barcelona","tag-fabrica-mecanizados-cnc","tag-fresadora","tag-mecanizado","tag-mecanizado-de-precision","tag-mecanizados-barcelona","tag-mecanizados-cnc","tag-mecanizados-cnc-barcelona","tag-mecanizados-de-precision","tag-mecanizados-de-precision-barcelona","tag-mecanizados-laboratorio","tag-mecanizados-laboratorio-barcelona","tag-mecanizados-precision","tag-mecanizados-precision-barcelona","tag-tipos-de-mecanizado-cnc"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 es una f\u00e1brica de mecanizados en Barcelona? - Mecanica Curiel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mecanicacuriel.com\/en\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es una f\u00e1brica de mecanizados en Barcelona? - Mecanica Curiel\" \/>\n<meta property=\"og:description\" content=\"Bienvenidos un d\u00eda m\u00e1s al blog de Mec\u00e1nica Curiel, una f\u00e1brica de mecanizados situada en Barcelona desde el a\u00f1o 1972, los cuales ofrecen a sus clientes la fabricaci\u00f3n y la construcci\u00f3n de diferentes tipos de mecanizados y de montajes de precisi\u00f3n. Pero todav\u00eda hay mucha gente en Barcelona que no conoce la gran importancia que tienen las f\u00e1bricas de mecanizados,Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mecanicacuriel.com\/en\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"Mecanica Curiel\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-31T08:33:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-31T17:06:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"621\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"carlos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"carlos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/\"},\"author\":{\"name\":\"carlos\",\"@id\":\"https:\/\/mecanicacuriel.com\/#\/schema\/person\/9f90f1e5315ecfc20531b1223566cad6\"},\"headline\":\"\u00bfQu\u00e9 es una f\u00e1brica de mecanizados en Barcelona?\",\"datePublished\":\"2017-07-31T08:33:42+00:00\",\"dateModified\":\"2018-10-31T17:06:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/\"},\"wordCount\":506,\"image\":{\"@id\":\"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-2-1.jpg\",\"keywords\":[\"barcelona\",\"cnc\",\"empresa de mecanizados\",\"empresa de mecanizados barcelona\",\"empresa mecanizados tarragona\",\"F\u00e1brica mecanizados Barcelona\",\"F\u00e1brica mecanizados CNC\",\"fresadora\",\"mecanizado\",\"mecanizado de precisi\u00f3n\",\"mecanizados barcelona\",\"mecanizados cnc\",\"mecanizados cnc barcelona\",\"mecanizados de precisi\u00f3n\",\"mecanizados de precisi\u00f3n Barcelona\",\"mecanizados laboratorio\",\"mecanizados laboratorio barcelona\",\"mecanizados precision\",\"mecanizados precision barcelona\",\"Tipos de mecanizado CNC\"],\"articleSection\":[\"empresa de mecanizados\",\"empresa mecanizados\",\"Empresa mecanizados Barcelona\",\"Empresa valvuleria Barcelona\",\"f\u00e1brica mecanizados barcelona\",\"mecanizados cnc barcelona\",\"mecanizados precision\",\"mecanizados precisi\u00f3n Barcelona\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/\",\"url\":\"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/\",\"name\":\"\u00bfQu\u00e9 es una f\u00e1brica de mecanizados en Barcelona? - Mecanica Curiel\",\"isPartOf\":{\"@id\":\"https:\/\/mecanicacuriel.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-2-1.jpg\",\"datePublished\":\"2017-07-31T08:33:42+00:00\",\"dateModified\":\"2018-10-31T17:06:27+00:00\",\"author\":{\"@id\":\"https:\/\/mecanicacuriel.com\/#\/schema\/person\/9f90f1e5315ecfc20531b1223566cad6\"},\"breadcrumb\":{\"@id\":\"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#primaryimage\",\"url\":\"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-2-1.jpg\",\"contentUrl\":\"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-2-1.jpg\",\"width\":960,\"height\":621,\"caption\":\"fabrica mecanizados barcelona (2)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/mecanicacuriel.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es una f\u00e1brica de mecanizados en Barcelona?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mecanicacuriel.com\/#website\",\"url\":\"https:\/\/mecanicacuriel.com\/\",\"name\":\"Mecanica Curiel\",\"description\":\"fabricaci\u00f3n y construcci\u00f3n de mecanizados y montajes de precisi\u00f3n.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mecanicacuriel.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mecanicacuriel.com\/#\/schema\/person\/9f90f1e5315ecfc20531b1223566cad6\",\"name\":\"carlos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/mecanicacuriel.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab10b60551e807f6b37d54bb09e40bc41b08e3828d46504634ad6f35da1b46dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab10b60551e807f6b37d54bb09e40bc41b08e3828d46504634ad6f35da1b46dc?s=96&d=mm&r=g\",\"caption\":\"carlos\"},\"url\":\"https:\/\/mecanicacuriel.com\/en\/author\/carlos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es una f\u00e1brica de mecanizados en Barcelona? - Mecanica Curiel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mecanicacuriel.com\/en\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/","og_locale":"en_GB","og_type":"article","og_title":"\u00bfQu\u00e9 es una f\u00e1brica de mecanizados en Barcelona? - Mecanica Curiel","og_description":"Bienvenidos un d\u00eda m\u00e1s al blog de Mec\u00e1nica Curiel, una f\u00e1brica de mecanizados situada en Barcelona desde el a\u00f1o 1972, los cuales ofrecen a sus clientes la fabricaci\u00f3n y la construcci\u00f3n de diferentes tipos de mecanizados y de montajes de precisi\u00f3n. Pero todav\u00eda hay mucha gente en Barcelona que no conoce la gran importancia que tienen las f\u00e1bricas de mecanizados,Read more","og_url":"https:\/\/mecanicacuriel.com\/en\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/","og_site_name":"Mecanica Curiel","article_published_time":"2017-07-31T08:33:42+00:00","article_modified_time":"2018-10-31T17:06:27+00:00","og_image":[{"width":960,"height":621,"url":"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-2-1.jpg","type":"image\/jpeg"}],"author":"carlos","twitter_card":"summary_large_image","twitter_misc":{"Written by":"carlos","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#article","isPartOf":{"@id":"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/"},"author":{"name":"carlos","@id":"https:\/\/mecanicacuriel.com\/#\/schema\/person\/9f90f1e5315ecfc20531b1223566cad6"},"headline":"\u00bfQu\u00e9 es una f\u00e1brica de mecanizados en Barcelona?","datePublished":"2017-07-31T08:33:42+00:00","dateModified":"2018-10-31T17:06:27+00:00","mainEntityOfPage":{"@id":"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/"},"wordCount":506,"image":{"@id":"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-2-1.jpg","keywords":["barcelona","cnc","empresa de mecanizados","empresa de mecanizados barcelona","empresa mecanizados tarragona","F\u00e1brica mecanizados Barcelona","F\u00e1brica mecanizados CNC","fresadora","mecanizado","mecanizado de precisi\u00f3n","mecanizados barcelona","mecanizados cnc","mecanizados cnc barcelona","mecanizados de precisi\u00f3n","mecanizados de precisi\u00f3n Barcelona","mecanizados laboratorio","mecanizados laboratorio barcelona","mecanizados precision","mecanizados precision barcelona","Tipos de mecanizado CNC"],"articleSection":["empresa de mecanizados","empresa mecanizados","Empresa mecanizados Barcelona","Empresa valvuleria Barcelona","f\u00e1brica mecanizados barcelona","mecanizados cnc barcelona","mecanizados precision","mecanizados precisi\u00f3n Barcelona"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/","url":"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/","name":"\u00bfQu\u00e9 es una f\u00e1brica de mecanizados en Barcelona? - Mecanica Curiel","isPartOf":{"@id":"https:\/\/mecanicacuriel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#primaryimage"},"image":{"@id":"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-2-1.jpg","datePublished":"2017-07-31T08:33:42+00:00","dateModified":"2018-10-31T17:06:27+00:00","author":{"@id":"https:\/\/mecanicacuriel.com\/#\/schema\/person\/9f90f1e5315ecfc20531b1223566cad6"},"breadcrumb":{"@id":"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#primaryimage","url":"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-2-1.jpg","contentUrl":"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2017\/07\/fabrica-mecanizados-barcelona-2-1.jpg","width":960,"height":621,"caption":"fabrica mecanizados barcelona (2)"},{"@type":"BreadcrumbList","@id":"https:\/\/mecanicacuriel.com\/2017\/07\/31\/que-es-una-fabrica-de-mecanizados-en-barcelona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mecanicacuriel.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es una f\u00e1brica de mecanizados en Barcelona?"}]},{"@type":"WebSite","@id":"https:\/\/mecanicacuriel.com\/#website","url":"https:\/\/mecanicacuriel.com\/","name":"Curiel Mechanics","description":"manufacturing and construction of precision machining and assembly.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mecanicacuriel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/mecanicacuriel.com\/#\/schema\/person\/9f90f1e5315ecfc20531b1223566cad6","name":"Carlos","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mecanicacuriel.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab10b60551e807f6b37d54bb09e40bc41b08e3828d46504634ad6f35da1b46dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab10b60551e807f6b37d54bb09e40bc41b08e3828d46504634ad6f35da1b46dc?s=96&d=mm&r=g","caption":"carlos"},"url":"https:\/\/mecanicacuriel.com\/en\/author\/carlos\/"}]}},"_links":{"self":[{"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/posts\/1337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/comments?post=1337"}],"version-history":[{"count":1,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/posts\/1337\/revisions"}],"predecessor-version":[{"id":1340,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/posts\/1337\/revisions\/1340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/media\/1339"}],"wp:attachment":[{"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/media?parent=1337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/categories?post=1337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/tags?post=1337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}