{"id":588,"date":"2016-06-23T08:35:50","date_gmt":"2016-06-23T08:35:50","guid":{"rendered":"http:\/\/mecanicacuriel.com\/?p=588"},"modified":"2018-10-31T17:15:29","modified_gmt":"2018-10-31T17:15:29","slug":"empresa-mecanizados-tarragona","status":"publish","type":"post","link":"https:\/\/mecanicacuriel.com\/en\/2016\/06\/23\/empresa-mecanizados-tarragona\/","title":{"rendered":"Machining company in Tarragona"},"content":{"rendered":"<h2 style=\"text-align: center;\"><u>\u00bfQu\u00e9 hacemos?<\/u><\/h2>\n<p>&nbsp;<\/p>\n<p>Hoy en el blog de Mec\u00e1nica Curiel os vamos a hablar de nuestra empresa, ya que somos los l\u00edderes en la construcci\u00f3n y montaje de <strong>mechanized<\/strong> in <strong>Tarragona<\/strong>, construimos todo tipo de instrumentos f\u00edsicos y de laboratorio, <strong>mechanized<\/strong> de precisi\u00f3n, utillajes, valvuler\u00eda especial y mucho m\u00e1s, pero siempre utilizando materiales de primera calidad y muy variados, por ejemplo, pl\u00e1sticos t\u00e9cnicos, latones, aleaciones de aluminio, bronces\u2026<\/p>\n<p>En nuestros m\u00e1s de cuarenta a\u00f1os de experiencia, hemos podido aprender y mejorar d\u00eda tras d\u00eda y por eso hoy somos el numero uno dentro del sector de <strong>mechanized<\/strong> en el \u00e1rea de Barcelona y <strong>Tarragona<\/strong>.<\/p>\n<p>Confeccionamos varios aparatos <strong>mechanized<\/strong>, que son muy \u00fatiles para que otras empresas puedan desarrollar su trabajo y puedan construir otros productos que son necesarios en la sociedad.<\/p>\n<p>Algunos de los <strong>mechanized<\/strong> que construimos para el \u00e1rea de <strong>Tarragona<\/strong> son:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"text-align: left;\"><strong>Machining<\/strong> en pl\u00e1sticos t\u00e9cnicos.<\/li>\n<li style=\"text-align: left;\">Carro lineal.<\/li>\n<li style=\"text-align: left;\">Moldes para fundici\u00f3n de lat\u00f3n por gravedad<\/li>\n<li style=\"text-align: left;\"><strong>Machining<\/strong> de cajas de pl\u00e1stico.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s de utilizar materiales de primera, utilizamos los mejores procesos productivos especializados y tenemos la infraestructura y los medios t\u00e9cnicos m\u00e1s actualizados, para garantizar a nuestros clientes de <strong>mechanized<\/strong> in <strong>Tarragona<\/strong>, la calidad y la fiabilidad que se merecen.<\/p>\n<p>Pero no nos conformamos con nuestro gran \u00e9xito en <strong>Tarragona<\/strong> y por eso seguimos trabajando en el sector de los <strong>mechanized<\/strong>, para mantener todos nuestros principios de seriedad, profesionalidad y compromiso que ofrecemos a todos nuestros clientes de <strong>Tarragona<\/strong>.<\/p>\n<p><a href=\"http:\/\/new.mecanicacuriel.palets-barcelona.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona.jpg\" rel=\"attachment wp-att-591\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-591 aligncenter\" src=\"http:\/\/new.mecanicacuriel.palets-barcelona.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona.jpg\" alt=\"empresa mecanizados tarragona\" width=\"575\" height=\"370\" srcset=\"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona.jpg 1000w, https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona-300x193.jpg 300w, https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona-768x495.jpg 768w\" sizes=\"auto, (max-width: 575px) 100vw, 575px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><u>Nuestro equipo<\/u><\/h2>\n<p>&nbsp;<\/p>\n<p>Con tal de ayudar y darles todo lo que necesitan a nuestros clientes de <strong>mechanized<\/strong> in <strong>Tarragona <\/strong>contamos con unos grandes profesionales que est\u00e1n a la altura de todo lo que necesiten ya que tienen una larga experiencia en este sector.<\/p>\n<p>Aunque sea un equipo humano de alto nivel, se siguen formando d\u00eda tras d\u00eda, para mejorar y ponerse al d\u00eda de los avances t\u00e9cnicos m\u00e1s modernos que salen al mercado.<\/p>\n<p>Por eso, gracias a la combinaci\u00f3n de nuestro equipo y de nuestros materiales de m\u00e1xima calidad, hoy en d\u00eda podemos presumir de ser una empresa de <strong>mechanized<\/strong> l\u00edder en <strong>Tarragona<\/strong> y con una trayectoria de m\u00e1s de cuarenta a\u00f1os.<\/p>","protected":false},"excerpt":{"rendered":"<p>What do we do? Today on the Mec\u00e1nica Curiel blog we are going to talk to you about our company, since we are the leaders in the construction and assembly of machining in Tarragona, we build all types of physical and laboratory instruments, precision machining, tools, special valves and much more. more, but always using top quality and very varied materials, for<\/p>\n<div class=\"h10\"><\/div>\n<p><a class=\"more-link1\" href=\"https:\/\/mecanicacuriel.com\/en\/2016\/06\/23\/empresa-mecanizados-tarragona\/\">Read more<\/a><\/p>","protected":false},"author":2,"featured_media":589,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3,4,6,7,17],"tags":[23,28,30,41,43,45,48],"class_list":["post-588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresa-de-mecanizados","category-empresa-de-mecanizados-cnc","category-empresa-mecanizados","category-empresa-mecanizados-precision","category-empresa-mecanizados-tarragona","category-mecanizados-tarragona","tag-empresa-de-mecanizados","tag-empresa-mecanizados-tarragona","tag-mecanizado","tag-mecanizados-laboratorio","tag-mecanizados-precision","tag-mecanizados-tarragona","tag-tarragona"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empresa de Mecanizados en Tarragona - Mecanica Curiel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mecanicacuriel.com\/en\/2016\/06\/23\/empresa-mecanizados-tarragona\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empresa de Mecanizados en Tarragona - Mecanica Curiel\" \/>\n<meta property=\"og:description\" content=\"\u00bfQu\u00e9 hacemos? &nbsp; Hoy en el blog de Mec\u00e1nica Curiel os vamos a hablar de nuestra empresa, ya que somos los l\u00edderes en la construcci\u00f3n y montaje de mecanizados en Tarragona, construimos todo tipo de instrumentos f\u00edsicos y de laboratorio, mecanizados de precisi\u00f3n, utillajes, valvuler\u00eda especial y mucho m\u00e1s, pero siempre utilizando materiales de primera calidad y muy variados, porRead more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mecanicacuriel.com\/en\/2016\/06\/23\/empresa-mecanizados-tarragona\/\" \/>\n<meta property=\"og:site_name\" content=\"Mecanica Curiel\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-23T08:35:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-31T17:15:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"alex\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"alex\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/\"},\"author\":{\"name\":\"alex\",\"@id\":\"https:\/\/mecanicacuriel.com\/#\/schema\/person\/3d096a733c15ebef35aa746377deab42\"},\"headline\":\"Empresa de Mecanizados en Tarragona\",\"datePublished\":\"2016-06-23T08:35:50+00:00\",\"dateModified\":\"2018-10-31T17:15:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/\"},\"wordCount\":393,\"image\":{\"@id\":\"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona2.jpg\",\"keywords\":[\"empresa de mecanizados\",\"empresa mecanizados tarragona\",\"mecanizado\",\"mecanizados laboratorio\",\"mecanizados precision\",\"mecanizados tarragona\",\"tarragona\"],\"articleSection\":[\"empresa de mecanizados\",\"Empresa de mecanizados CNC\",\"empresa mecanizados\",\"Empresa mecanizados precisi\u00f3n\",\"empresa mecanizados tarragona\",\"mecanizados tarragona\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/\",\"url\":\"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/\",\"name\":\"Empresa de Mecanizados en Tarragona - Mecanica Curiel\",\"isPartOf\":{\"@id\":\"https:\/\/mecanicacuriel.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona2.jpg\",\"datePublished\":\"2016-06-23T08:35:50+00:00\",\"dateModified\":\"2018-10-31T17:15:29+00:00\",\"author\":{\"@id\":\"https:\/\/mecanicacuriel.com\/#\/schema\/person\/3d096a733c15ebef35aa746377deab42\"},\"breadcrumb\":{\"@id\":\"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#primaryimage\",\"url\":\"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona2.jpg\",\"contentUrl\":\"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona2.jpg\",\"width\":2560,\"height\":1600,\"caption\":\"empresa mecanizados tarragona2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/mecanicacuriel.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresa de Mecanizados en Tarragona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mecanicacuriel.com\/#website\",\"url\":\"https:\/\/mecanicacuriel.com\/\",\"name\":\"Mecanica Curiel\",\"description\":\"fabricaci\u00f3n y construcci\u00f3n de mecanizados y montajes de precisi\u00f3n.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mecanicacuriel.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mecanicacuriel.com\/#\/schema\/person\/3d096a733c15ebef35aa746377deab42\",\"name\":\"alex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/mecanicacuriel.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1e7ff198c5c4a8321098d203c97fde3f715d0e63eb61b5e3fc2c47d1f8af4867?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1e7ff198c5c4a8321098d203c97fde3f715d0e63eb61b5e3fc2c47d1f8af4867?s=96&d=mm&r=g\",\"caption\":\"alex\"},\"url\":\"https:\/\/mecanicacuriel.com\/en\/author\/alex\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empresa de Mecanizados en Tarragona - Mecanica Curiel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mecanicacuriel.com\/en\/2016\/06\/23\/empresa-mecanizados-tarragona\/","og_locale":"en_GB","og_type":"article","og_title":"Empresa de Mecanizados en Tarragona - Mecanica Curiel","og_description":"\u00bfQu\u00e9 hacemos? &nbsp; Hoy en el blog de Mec\u00e1nica Curiel os vamos a hablar de nuestra empresa, ya que somos los l\u00edderes en la construcci\u00f3n y montaje de mecanizados en Tarragona, construimos todo tipo de instrumentos f\u00edsicos y de laboratorio, mecanizados de precisi\u00f3n, utillajes, valvuler\u00eda especial y mucho m\u00e1s, pero siempre utilizando materiales de primera calidad y muy variados, porRead more","og_url":"https:\/\/mecanicacuriel.com\/en\/2016\/06\/23\/empresa-mecanizados-tarragona\/","og_site_name":"Mecanica Curiel","article_published_time":"2016-06-23T08:35:50+00:00","article_modified_time":"2018-10-31T17:15:29+00:00","og_image":[{"width":2560,"height":1600,"url":"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona2.jpg","type":"image\/jpeg"}],"author":"alex","twitter_card":"summary_large_image","twitter_misc":{"Written by":"alex","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#article","isPartOf":{"@id":"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/"},"author":{"name":"alex","@id":"https:\/\/mecanicacuriel.com\/#\/schema\/person\/3d096a733c15ebef35aa746377deab42"},"headline":"Empresa de Mecanizados en Tarragona","datePublished":"2016-06-23T08:35:50+00:00","dateModified":"2018-10-31T17:15:29+00:00","mainEntityOfPage":{"@id":"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/"},"wordCount":393,"image":{"@id":"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#primaryimage"},"thumbnailUrl":"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona2.jpg","keywords":["empresa de mecanizados","empresa mecanizados tarragona","mecanizado","mecanizados laboratorio","mecanizados precision","mecanizados tarragona","tarragona"],"articleSection":["empresa de mecanizados","Empresa de mecanizados CNC","empresa mecanizados","Empresa mecanizados precisi\u00f3n","empresa mecanizados tarragona","mecanizados tarragona"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/","url":"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/","name":"Empresa de Mecanizados en Tarragona - Mecanica Curiel","isPartOf":{"@id":"https:\/\/mecanicacuriel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#primaryimage"},"image":{"@id":"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#primaryimage"},"thumbnailUrl":"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona2.jpg","datePublished":"2016-06-23T08:35:50+00:00","dateModified":"2018-10-31T17:15:29+00:00","author":{"@id":"https:\/\/mecanicacuriel.com\/#\/schema\/person\/3d096a733c15ebef35aa746377deab42"},"breadcrumb":{"@id":"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#primaryimage","url":"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona2.jpg","contentUrl":"https:\/\/mecanicacuriel.com\/wp-content\/uploads\/2016\/06\/empresa-mecanizados-tarragona2.jpg","width":2560,"height":1600,"caption":"empresa mecanizados tarragona2"},{"@type":"BreadcrumbList","@id":"https:\/\/mecanicacuriel.com\/2016\/06\/23\/empresa-mecanizados-tarragona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mecanicacuriel.com\/"},{"@type":"ListItem","position":2,"name":"Empresa de Mecanizados en Tarragona"}]},{"@type":"WebSite","@id":"https:\/\/mecanicacuriel.com\/#website","url":"https:\/\/mecanicacuriel.com\/","name":"Curiel Mechanics","description":"manufacturing and construction of precision machining and assembly.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mecanicacuriel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/mecanicacuriel.com\/#\/schema\/person\/3d096a733c15ebef35aa746377deab42","name":"Alex","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mecanicacuriel.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1e7ff198c5c4a8321098d203c97fde3f715d0e63eb61b5e3fc2c47d1f8af4867?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1e7ff198c5c4a8321098d203c97fde3f715d0e63eb61b5e3fc2c47d1f8af4867?s=96&d=mm&r=g","caption":"alex"},"url":"https:\/\/mecanicacuriel.com\/en\/author\/alex\/"}]}},"_links":{"self":[{"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/posts\/588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/comments?post=588"}],"version-history":[{"count":1,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/posts\/588\/revisions"}],"predecessor-version":[{"id":849,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/posts\/588\/revisions\/849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/media\/589"}],"wp:attachment":[{"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/media?parent=588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/categories?post=588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mecanicacuriel.com\/en\/wp-json\/wp\/v2\/tags?post=588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}